{"id":6654,"date":"2023-08-10T09:17:53","date_gmt":"2023-08-10T07:17:53","guid":{"rendered":"http:\/\/192.168.0.6\/solari-new\/?page_id=6654"},"modified":"2023-11-21T14:30:01","modified_gmt":"2023-11-21T13:30:01","slug":"empowering-sustainability","status":"publish","type":"page","link":"https:\/\/homeadaptfrance.com\/index.php\/empowering-sustainability\/","title":{"rendered":"Pompe \u00e0 chaleur"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6654\" class=\"elementor elementor-6654\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a770b3c elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a770b3c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-1181b60\" data-id=\"1181b60\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de6daad elementor-widget elementor-widget-image\" data-id=\"de6daad\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 26-03-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"944\" height=\"550\" src=\"https:\/\/homeadaptfrance.com\/wp-content\/uploads\/2023\/08\/09-1-1.jpg\" class=\"attachment-full size-full wp-image-6573\" alt=\"\" srcset=\"https:\/\/homeadaptfrance.com\/wp-content\/uploads\/2023\/08\/09-1-1.jpg 944w, https:\/\/homeadaptfrance.com\/wp-content\/uploads\/2023\/08\/09-1-1-600x350.jpg 600w, https:\/\/homeadaptfrance.com\/wp-content\/uploads\/2023\/08\/09-1-1-300x175.jpg 300w, https:\/\/homeadaptfrance.com\/wp-content\/uploads\/2023\/08\/09-1-1-768x447.jpg 768w\" sizes=\"(max-width: 944px) 100vw, 944px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7911bd6 elementor-widget elementor-widget-heading\" data-id=\"7911bd6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 26-03-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h3 class=\"elementor-heading-title elementor-size-default\">La pompe \u00e0 chaleur une \u00e9cologie et efficacit\u00e9 pour un confort durable<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e77d468 elementor-widget elementor-widget-text-editor\" data-id=\"e77d468\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 26-03-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>La pompe \u00e0 chaleur repr\u00e9sente une solution innovante et \u00e9cologique dans le domaine du chauffage. Fonctionnant de mani\u00e8re ing\u00e9nieuse, elle extrait la chaleur de l&#8217;air, de l&#8217;eau ou du sol pour la redistribuer \u00e0 l&#8217;int\u00e9rieur d&#8217;un espace, que ce soit pour le chauffage ou le refroidissement. Ce syst\u00e8me pr\u00e9sente de nombreux avantages positifs. Tout d&#8217;abord, il utilise des sources d&#8217;\u00e9nergie renouvelables, r\u00e9duisant ainsi notre d\u00e9pendance aux combustibles fossiles et contribuant \u00e0 la diminution des \u00e9missions de gaz \u00e0 effet de serre. De plus, la pompe \u00e0 chaleur est extr\u00eamement efficace, transformant chaque unit\u00e9 d&#8217;\u00e9nergie consomm\u00e9e en plusieurs unit\u00e9s de chaleur. Elle offre \u00e9galement des \u00e9conomies substantielles sur les co\u00fbts \u00e9nerg\u00e9tiques \u00e0 long terme. En adoptant cette technologie, nous investissons dans un avenir plus durable tout en profitant d&#8217;un confort thermique optimal.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b80fe04 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b80fe04\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9f0e358\" data-id=\"9f0e358\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-138cb26 elementor-widget elementor-widget-image\" data-id=\"138cb26\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"386\" height=\"260\" src=\"https:\/\/homeadaptfrance.com\/wp-content\/uploads\/2023\/08\/10-1.jpg\" class=\"attachment-large size-large wp-image-6575\" alt=\"\" srcset=\"https:\/\/homeadaptfrance.com\/wp-content\/uploads\/2023\/08\/10-1.jpg 386w, https:\/\/homeadaptfrance.com\/wp-content\/uploads\/2023\/08\/10-1-300x202.jpg 300w\" sizes=\"(max-width: 386px) 100vw, 386px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9c91b42\" data-id=\"9c91b42\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed710ec elementor-widget elementor-widget-react-heading\" data-id=\"ed710ec\" data-element_type=\"widget\" data-widget_type=\"react-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\t\t<div class=\"react-heading default  title-border-\">\r\n\t\t\t<div class=\"title-inner \">\r\n\t\t\t\t<div class=\"skew-up \"><h4 class=\"title word-line\">Avantages environnementaux<\/h4><\/div>\r\n\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"description\">\r\n\t\t\t\t\t<p>La pompe \u00e0 chaleur contribue positivement \u00e0 l'environnement en exploitant des sources d'\u00e9nergie renouvelables telles que l'air, l'eau ou le sol. En extrayant la chaleur de ces ressources, elle r\u00e9duit la d\u00e9pendance aux combustibles fossiles, diminuant ainsi les \u00e9missions de gaz \u00e0 effet de serre responsables du changement climatique. Son efficacit\u00e9 \u00e9nerg\u00e9tique \u00e9lev\u00e9e permet \u00e9galement de consommer moins d'\u00e9lectricit\u00e9, favorisant une empreinte carbone r\u00e9duite et une transition vers des solutions de chauffage et de refroidissement plus durables.<\/p>\t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n\t\t\t\t<div class=\"rt-button\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<a class=\"readon react_button elementor-animation-\" href=\"\" >\r\n\t\t\t\t\t\t<span >View More<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\r\n\t\t<script>\r\n\t\t\tjQuery(document).ready(function(){\r\n\t\t\tlet addAnimation = function () {\r\n\t\t\tjQuery(\".skew-up\").each(function (index) {\r\n\t\t\t\tconst text = new SplitType(jQuery(this), {\r\n\t\t\t\ttypes: \"lines, words\",\r\n\t\t\t\tlineClass: \"word-line\"\r\n\t\t\t\t});    let textInstance = jQuery(this);\r\n\t\t\t\tlet line = textInstance.find(\".word-line\");\r\n\t\t\t\tlet word = line.find(\".word\");    let tl = gsap.timeline({\r\n\t\t\t\tscrollTrigger: {\r\n\t\t\t\t\ttrigger: textInstance,\r\n\t\t\t\t\tstart: \"top 85%\",\r\n\t\t\t\t\tend: \"top 100%\",\r\n\t\t\t\t\tonComplete: function () {\r\n\t\t\t\t\tjQuery(textInstance).removeClass(\"skew-up\");\r\n\t\t\t\t\t}\r\n\t\t\t\t}\r\n\t\t\t\t});    tl.set(textInstance, { opacity: 1 }).from(word, {\r\n\t\t\t\ty: \"100%\",\r\n\t\t\t\tskewX: \"-5\",\r\n\t\t\t\tduration: 2,\r\n\t\t\t\tstagger: 0.03,\r\n\t\t\t\tease: \"expo.out\"\r\n\t\t\t\t});\r\n\t\t\t});\r\n\t\t\t};addAnimation();window.addEventListener(\"resize\", function (event) {\r\n\t\t\t\tif (jQuery(window).width() >= 992) {addAnimation(); }\r\n\t\t\t});\r\n\t\t});\r\n   \r\n\t\t<\/script>\r\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0340af9 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0340af9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2e6a9e1\" data-id=\"2e6a9e1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b27c953 elementor-widget elementor-widget-heading\" data-id=\"b27c953\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00c9conomies financi\u00e8re <\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-777b97d elementor-widget elementor-widget-text-editor\" data-id=\"777b97d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>L&#8217;acquisition d&#8217;une pompe \u00e0 chaleur offre des avantages financiers consid\u00e9rables \u00e0 long terme. Gr\u00e2ce \u00e0 son efficacit\u00e9 \u00e9nerg\u00e9tique \u00e9lev\u00e9e, elle permet de r\u00e9duire significativement les co\u00fbts de chauffage et de climatisation, entra\u00eenant des \u00e9conomies substantielles sur les factures \u00e9nerg\u00e9tiques. De plus, l&#8217;utilisation de sources d&#8217;\u00e9nergie renouvelables contribue \u00e0 une meilleure gestion des d\u00e9penses li\u00e9es aux combustibles fossiles. Bien que l&#8217;investissement initial puisse \u00eatre plus \u00e9lev\u00e9, les \u00e9conomies r\u00e9alis\u00e9es au fil du temps font de la pompe \u00e0 chaleur une option rentable, offrant un retour sur investissement attractif tout en favorisant une approche \u00e9co-responsable.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3b88aff elementor-section-content-middle ssss elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b88aff\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a53601d\" data-id=\"a53601d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38d1e74 elementor-widget elementor-widget-rt-service-grid\" data-id=\"38d1e74\" data-element_type=\"widget\" data-widget_type=\"rt-service-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\t\t\r\n\r\n\r\n\t\t\r\n\r\n\t\t\r\n\r\n\t\t\r\n\r\n\t\t\r\n\t\t\t<div class=\"single-feature-soalri-3\">\r\n\t\t\t\t<div class=\"icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"51\" height=\"36\" viewBox=\"0 0 51 36\" fill=\"none\"><path d=\"M50.1691 18.2293L35.9942 4.14235C35.9658 4.11417 35.9446 4.10087 35.921 4.08678C35.7855 3.97957 35.6186 3.91304 35.4374 3.91304H33.401L35.9942 1.33591C36.2194 1.11209 36.2871 0.775565 36.1651 0.482869C36.0438 0.190174 35.7564 0 35.4374 0H14.9626C14.7531 0 14.5531 0.0821741 14.4058 0.229305L0.230885 14.3163C0.0056615 14.5401 -0.0620631 14.8766 0.0599987 15.1693C0.18206 15.462 0.469496 15.6522 0.787644 15.6522H2.82411L0.230885 18.2293C0.0056615 18.4531 -0.0620631 18.7897 0.0599987 19.0823C0.18206 19.375 0.469496 19.5652 0.787644 19.5652H2.36263V35.2174C2.36263 35.6502 2.71465 36 3.15013 36H47.2499C47.6854 36 48.0374 35.6502 48.0374 35.2174V19.5652H49.6124C49.9305 19.5652 50.2179 19.375 50.34 19.0823C50.4621 18.7897 50.3943 18.4531 50.1691 18.2293ZM28.024 7.04348H23.1635L28.676 1.56522H33.5364L28.024 7.04348ZM8.98862 14.087L14.5011 8.6087H19.3615L13.849 14.087H8.98862ZM26.449 1.56522L20.9365 7.04348H16.0761L21.5885 1.56522H26.449ZM21.5885 8.6087H26.449L20.9365 14.087H16.0761L21.5885 8.6087ZM15.2886 1.56522H19.3615L13.849 7.04348H9.77611L15.2886 1.56522ZM8.20112 8.6087H12.2741L6.76158 14.087H2.68866L8.20112 8.6087ZM5.05114 15.6522H21.2625C21.472 15.6522 21.6712 15.5692 21.8193 15.4229L31.826 5.47826H33.5364L20.9365 18H2.68866L5.05114 15.6522ZM3.93763 19.5652H22.8375V34.4348H3.93763V19.5652ZM32.2875 34.4348V23.4783H38.5874V34.4348H32.2875ZM47.2499 18C46.8144 18 46.4624 18.3498 46.4624 18.7826V34.4348H40.1624V22.6957C40.1624 22.2629 39.8104 21.913 39.3749 21.913H31.5C31.0645 21.913 30.7125 22.2629 30.7125 22.6957V34.4348H24.4125V18.7826C24.4125 18.3498 24.0605 18 23.625 18H23.1635L35.4374 5.80226L47.7113 18H47.2499Z\" fill=\"#4AAB3D\"><\/path><path d=\"M35.4374 11.7391C33.2663 11.7391 31.5 13.4945 31.5 15.6522C31.5 17.8098 33.2663 19.5652 35.4374 19.5652C37.6086 19.5652 39.3749 17.8098 39.3749 15.6522C39.3749 13.4945 37.6086 11.7391 35.4374 11.7391ZM35.4374 18C34.1349 18 33.075 16.9466 33.075 15.6522C33.075 14.3577 34.1349 13.3043 35.4374 13.3043C36.74 13.3043 37.7999 14.3577 37.7999 15.6522C37.7999 16.9474 36.7407 18 35.4374 18Z\" fill=\"#4AAB3D\"><\/path><path d=\"M20.475 21.913H6.30011C5.86463 21.913 5.51262 22.2629 5.51262 22.6957V30.5217C5.51262 30.9545 5.86463 31.3043 6.30011 31.3043H20.475C20.9105 31.3043 21.2625 30.9545 21.2625 30.5217V22.6957C21.2625 22.2637 20.9105 21.913 20.475 21.913ZM7.08761 23.4783H12.6001V29.7391H7.08761V23.4783ZM19.6875 29.7391H14.1751V23.4783H19.6875V29.7391Z\" fill=\"#4AAB3D\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<h5 class=\"title\">\r\n\t\t\t\t\t\t\t\t\t\t\tStep One\t\t\t\t\t\t\t\t\t<\/h5>\r\n\t\t\t\t<p class=\"disc\">\r\n\t\t\t\t\t\t\t\t\t\t\tTactical services through market web services\t\t\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\r\n\r\n\t\t\r\n\t\t\r\n\r\n\t\t\r\n\r\n\t\t\r\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4355d5b\" data-id=\"4355d5b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3937068 elementor-widget elementor-widget-rt-service-grid\" data-id=\"3937068\" data-element_type=\"widget\" data-widget_type=\"rt-service-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\t\t\r\n\r\n\r\n\t\t\r\n\r\n\t\t\r\n\r\n\t\t\r\n\r\n\t\t\r\n\t\t\t<div class=\"single-feature-soalri-3\">\r\n\t\t\t\t<div class=\"icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"47\" height=\"47\" viewBox=\"0 0 47 47\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M36.0892 5.03606C32.8467 5.03606 30.2142 7.66861 30.2142 10.911C30.2142 14.1535 32.8467 16.786 36.0892 16.786C39.3316 16.786 41.9641 14.1535 41.9641 10.911C41.9641 7.66861 39.3316 5.03606 36.0892 5.03606ZM36.0892 6.71463C38.405 6.71463 40.2855 8.59518 40.2855 10.911C40.2855 13.2269 38.405 15.1074 36.0892 15.1074C33.7733 15.1074 31.8928 13.2269 31.8928 10.911C31.8928 8.59518 33.7733 6.71463 36.0892 6.71463Z\" fill=\"#4AAB3D\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M36.9282 20.9823V19.3037C36.9282 18.8404 36.5521 18.4644 36.0889 18.4644C35.6257 18.4644 35.2496 18.8404 35.2496 19.3037V20.9823C35.2496 21.4456 35.6257 21.8216 36.0889 21.8216C36.5521 21.8216 36.9282 21.4456 36.9282 20.9823Z\" fill=\"#4AAB3D\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M44.2359 17.8711L42.5573 16.1925C42.2298 15.8652 41.6979 15.8652 41.3703 16.1925C41.0428 16.5198 41.0428 17.0519 41.3703 17.3793L43.0489 19.0578C43.3765 19.3851 43.9083 19.3851 44.2359 19.0578C44.5634 18.7305 44.5634 18.1984 44.2359 17.8711Z\" fill=\"#4AAB3D\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M46.1607 10.0716H44.4822C44.019 10.0716 43.6429 10.4476 43.6429 10.9109C43.6429 11.3742 44.019 11.7502 44.4822 11.7502H46.1607C46.6239 11.7502 47 11.3742 47 10.9109C47 10.4476 46.6239 10.0716 46.1607 10.0716Z\" fill=\"#4AAB3D\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M43.0489 2.76402L41.3703 4.44258C41.0428 4.7699 41.0428 5.302 41.3703 5.62932C41.6979 5.95664 42.2298 5.95664 42.5573 5.62932L44.2359 3.95076C44.5634 3.62344 44.5634 3.09134 44.2359 2.76402C43.9083 2.4367 43.3765 2.4367 43.0489 2.76402Z\" fill=\"#4AAB3D\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M30.8074 4.44258L29.1289 2.76402C28.8013 2.4367 28.2694 2.4367 27.9419 2.76402C27.6144 3.09134 27.6144 3.62344 27.9419 3.95076L29.6204 5.62932C29.948 5.95664 30.4799 5.95664 30.8074 5.62932C31.1349 5.302 31.1349 4.7699 30.8074 4.44258Z\" fill=\"#4AAB3D\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M35.2496 0.839403V2.51793C35.2496 2.98123 35.6257 3.35734 36.0889 3.35734C36.5521 3.35734 36.9282 2.98123 36.9282 2.51793V0.839403C36.9282 0.376103 36.5521 0 36.0889 0C35.6257 0 35.2496 0.376103 35.2496 0.839403Z\" fill=\"#4AAB3D\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M29.6204 16.1925L27.9419 17.8711C27.6144 18.1984 27.6144 18.7305 27.9419 19.0578C28.2694 19.3851 28.8013 19.3851 29.1289 19.0578L30.8074 17.3793C31.1349 17.0519 31.1349 16.5198 30.8074 16.1925C30.4799 15.8652 29.948 15.8652 29.6204 16.1925Z\" fill=\"#4AAB3D\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M27.6966 10.0716H26.018C25.5548 10.0716 25.1788 10.4476 25.1788 10.9109C25.1788 11.3742 25.5548 11.7502 26.018 11.7502H27.6966C28.1598 11.7502 28.5359 11.3742 28.5359 10.9109C28.5359 10.4476 28.1598 10.0716 27.6966 10.0716Z\" fill=\"#4AAB3D\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M2.28206 25.1787L0.0252364 16.1505C-0.0377095 15.8996 0.0185219 15.6336 0.177985 15.4304C0.336608 15.2265 0.580839 15.1073 0.839336 15.1073H26.0177C26.481 15.1073 26.857 15.4833 26.857 15.9466C26.857 16.4099 26.481 16.7859 26.0177 16.7859H19.5393L21.6375 25.1787H29.1398L28.3509 22.0255C28.2384 21.5757 28.512 21.1199 28.9619 21.0075C29.4109 20.895 29.8675 21.1686 29.9799 21.6176L30.8696 25.1787H37.5318L37.3731 24.5434C37.2607 24.0935 37.5343 23.6378 37.9833 23.5253C38.4331 23.4128 38.8889 23.6865 39.0013 24.1355L39.2624 25.1787H40.2854C40.7487 25.1787 41.1247 25.5547 41.1247 26.018C41.1247 26.4813 40.7487 26.8573 40.2854 26.8573H39.682L41.9388 35.8854C42.0018 36.1363 41.9455 36.4024 41.7861 36.6055C41.6274 36.8095 41.3832 36.9286 41.1247 36.9286H24.3391V45.3214H46.1604C46.6237 45.3214 46.9997 45.6974 46.9997 46.1607C46.9997 46.624 46.6237 47 46.1604 47H0.839336C0.376055 47 5.78268e-05 46.624 5.78268e-05 46.1607C5.78268e-05 45.6974 0.376055 45.3214 0.839336 45.3214H17.6249V36.9286H5.87501C5.48978 36.9286 5.15407 36.6668 5.06091 36.2933L2.7017 26.8573H1.67862C1.21533 26.8573 0.839336 26.4813 0.839336 26.018C0.839336 25.5547 1.21533 25.1787 1.67862 25.1787H2.28206ZM19.3035 36.9286V45.3214H22.6606V36.9286H19.3035ZM13.1927 35.2501L11.0945 26.8573H4.43229L6.53048 35.2501H13.1927ZM12.8251 26.8573L14.9233 35.2501H22.4247L20.3265 26.8573H12.8251ZM22.0571 26.8573L24.1553 35.2501H31.6568L29.5586 26.8573H22.0571ZM37.9514 26.8573H31.2892L33.3874 35.2501H40.0496L37.9514 26.8573ZM1.91445 16.7859L4.01265 25.1787H10.6757L8.57749 16.7859H1.91445ZM10.3072 16.7859L12.4054 25.1787H19.9077L17.8095 16.7859H10.3072Z\" fill=\"#4AAB3D\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<h5 class=\"title\">\r\n\t\t\t\t\t\t\t\t\t\t\tStep Two\t\t\t\t\t\t\t\t\t<\/h5>\r\n\t\t\t\t<p class=\"disc\">\r\n\t\t\t\t\t\t\t\t\t\t\tTactical services through market web services\t\t\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\r\n\r\n\t\t\r\n\t\t\r\n\r\n\t\t\r\n\r\n\t\t\r\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ca42bb6\" data-id=\"ca42bb6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9e4949 elementor-widget elementor-widget-rt-service-grid\" data-id=\"b9e4949\" data-element_type=\"widget\" data-widget_type=\"rt-service-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\t\t\r\n\r\n\r\n\t\t\r\n\r\n\t\t\r\n\r\n\t\t\r\n\r\n\t\t\r\n\t\t\t<div class=\"single-feature-soalri-3\">\r\n\t\t\t\t<div class=\"icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"46\" height=\"46\" viewBox=\"0 0 46 46\" fill=\"none\"><path d=\"M36.339 21.9L36.8359 20.4494L38.2869 20.9463L37.79 22.3969L36.339 21.9Z\" fill=\"#4AAB3D\"><\/path><path d=\"M45.2333 41.4002H43.7V36.0335H44.4667C44.67 36.0335 44.865 35.9528 45.0088 35.809C45.1526 35.6652 45.2333 35.4702 45.2333 35.2669V29.1335C45.2333 28.9302 45.1526 28.7352 45.0088 28.5914C44.865 28.4477 44.67 28.3669 44.4667 28.3669H43.7V18.7282C44.0543 17.9526 44.3632 17.1571 44.6254 16.3458C46.2725 11.2622 46.4372 6.35409 45.1151 1.75784C45.0692 1.59789 44.9725 1.45723 44.8395 1.35714C44.7066 1.25704 44.5447 1.20296 44.3783 1.20306H40.5727C40.4096 1.20299 40.2507 1.25494 40.1192 1.35135C39.9876 1.44775 39.8902 1.5836 39.8412 1.73915L37.1309 10.3258L7.10585 0.041465C7.01058 0.00879203 6.90981 -0.00479036 6.80929 0.00149402C6.70878 0.00777839 6.61048 0.0338063 6.52003 0.0780907C6.42957 0.122375 6.34873 0.184048 6.28211 0.259586C6.2155 0.335124 6.16442 0.423047 6.1318 0.518331L4.64121 4.87012C4.6085 4.96536 4.59489 5.06612 4.60116 5.16663C4.60743 5.26714 4.63346 5.36543 4.67775 5.45587C4.72204 5.54631 4.78373 5.62713 4.85928 5.69371C4.93484 5.76029 5.02278 5.81132 5.11807 5.84388L19.1757 10.6591L19.5123 13.1639C19.371 13.2557 19.2642 13.3918 19.2086 13.5509C16.3891 21.7524 11.8717 34.9865 10.9171 38.3333H9.2C8.99667 38.3333 8.80166 38.4141 8.65788 38.5579C8.51411 38.7017 8.43333 38.8967 8.43333 39.1V41.4H0.766667C0.563334 41.4 0.368329 41.4808 0.224551 41.6246C0.0807735 41.7683 0 41.9633 0 42.1667V45.2333C0 45.4367 0.0807735 45.6317 0.224551 45.7754C0.368329 45.9192 0.563334 46 0.766667 46H45.2333C45.4367 46 45.6317 45.9192 45.7754 45.7754C45.9192 45.6317 46 45.4367 46 45.2333V42.1669C46 41.9635 45.9192 41.7685 45.7754 41.6247C45.6317 41.481 45.4367 41.4002 45.2333 41.4002ZM43.7 34.5002H42.1667V29.9002H43.7V34.5002ZM42.1667 28.3669H41.4C41.1967 28.3669 41.0017 28.4477 40.8579 28.5914C40.7141 28.7352 40.6333 28.9302 40.6333 29.1335V35.2669C40.6333 35.4702 40.7141 35.6652 40.8579 35.809C41.0017 35.9528 41.1967 36.0335 41.4 36.0335H42.1667V41.4002H28.3667V39.1002C28.3667 38.8969 28.2859 38.7019 28.1421 38.5581C27.9983 38.4143 27.8033 38.3335 27.6 38.3335H26.8333V13.9344L27.3252 13.4506L35.2841 16.1769L32.2352 25.8369C32.1757 26.0255 32.1914 26.2298 32.279 26.4072C32.3666 26.5845 32.5194 26.7211 32.7053 26.7884L34.5614 27.4604C34.6699 27.4996 34.7857 27.5139 34.9005 27.5021C35.0152 27.4904 35.1258 27.453 35.224 27.3926C37.9423 25.7241 40.3041 24.096 42.1667 21.4311V28.3669ZM16.0425 27.5906C16.0621 27.5922 16.0799 27.6002 16.1 27.6002H22.8188L14.67 31.6747C15.096 30.4004 15.5593 29.0226 16.0425 27.5906ZM18.1203 21.4669H23.3578L16.7358 25.5421C17.1911 24.1981 17.6564 22.8286 18.1203 21.4669ZM24.4034 16.1516C24.6531 16.015 24.8839 15.8462 25.0896 15.6495L25.3 15.4426V19.9336H19.7813L24.4034 16.1516ZM25.3 26.0669H18.8088L25.3 22.0723V26.0669ZM25.3 32.2002H17.0479L25.3 28.0741V32.2002ZM13.9845 33.7335H22.27L12.6683 37.7764C12.9716 36.8106 13.4289 35.4097 13.9845 33.7335ZM25.3 34.1216V38.3335H15.2966L25.3 34.1216ZM41.1349 2.7362H43.7929C44.8612 6.87418 44.6516 11.2907 43.167 15.8728C42.8915 16.7361 42.5597 17.5804 42.1737 18.4002H42.1667V18.4159C40.5713 21.7568 38.3123 23.6682 34.7351 25.8917L33.9191 25.5963L36.9602 15.9617C36.965 15.9489 36.9756 15.9395 36.9794 15.9266L38.3623 11.5374C38.3652 11.5278 38.3623 11.5187 38.3653 11.5093L41.1349 2.7362ZM6.34072 4.64184L7.33422 1.74059L36.6693 11.7884L35.7458 14.7137L27.3738 11.8461C27.2391 11.8001 27.0943 11.7925 26.9555 11.8241C26.8167 11.8557 26.6895 11.9253 26.588 12.0251L24.4222 14.1558L23.5436 14.8745C23.3009 14.9923 23.0337 15.0507 22.764 15.0448C22.4943 15.039 22.2299 14.9691 21.9925 14.841C21.7552 14.7128 21.5517 14.53 21.3989 14.3078C21.2461 14.0855 21.1483 13.8301 21.1136 13.5626L20.6329 9.98521C20.6139 9.84415 20.556 9.71116 20.4657 9.60114C20.3754 9.49112 20.2562 9.40842 20.1215 9.3623L6.34072 4.64184ZM20.2296 15.2975C20.6054 15.7931 21.1163 16.1696 21.701 16.3818L19.1407 18.4769C19.5139 17.3853 19.8788 16.3197 20.2296 15.2975ZM9.96667 39.8669H26.8333V41.4002H9.96667V39.8669ZM44.4667 44.4669H1.53333V42.9335H44.4667V44.4669Z\" fill=\"#4AAB3D\"><\/path><path d=\"M22.025 13.2553L22.5219 11.8047L23.9729 12.3017L23.476 13.7523L22.025 13.2553Z\" fill=\"#4AAB3D\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<h5 class=\"title\">\r\n\t\t\t\t\t\t\t\t\t\t\tStep Three\t\t\t\t\t\t\t\t\t<\/h5>\r\n\t\t\t\t<p class=\"disc\">\r\n\t\t\t\t\t\t\t\t\t\t\tTactical services through market web services\t\t\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\r\n\r\n\t\t\r\n\t\t\r\n\r\n\t\t\r\n\r\n\t\t\r\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f37e430 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f37e430\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-566d863\" data-id=\"566d863\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7fe96fb elementor-widget elementor-widget-text-editor\" data-id=\"7fe96fb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"disc\">Conveniently predominate revolutionary quality vectors through future-proof manufactured products. Objectively envisioneer high in convergence through collaborative networks. Interactively generate B2C tailers for business data restore fully researched relationships through<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2f79880\" data-id=\"2f79880\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fd8b8d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fd8b8d5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c27f6e2\" data-id=\"c27f6e2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f422fd9 elementor-widget elementor-widget-heading\" data-id=\"f422fd9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Nos Services<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99b6bd5 hfe-nav-menu__align-left elementor-widget elementor-widget-navigation-menu\" data-id=\"99b6bd5\" data-element_type=\"widget\" data-settings=\"{&quot;menu_space_between_margin&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:25,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:18,&quot;sizes&quot;:[]},&quot;meniu_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;30&quot;,&quot;right&quot;:&quot;30&quot;,&quot;bottom&quot;:&quot;30&quot;,&quot;left&quot;:&quot;30&quot;,&quot;isLinked&quot;:true},&quot;padding_horizontal_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between_margin_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between_margin_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;meniu_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;meniu_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;padding_horizontal_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"navigation-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t<div class=\"menu-area vertical expand-on-click separator_ \">         \r\n\t\t<div class=\"menu_one icon1 no\">\t\t\t\t\t\t\t \r\n\t\t\t<div class=\"col-cell menu-responsive  right_icon_yes left_icon_no\">  \r\n\t\t\t\t\t\t\t\t\t<nav class=\"nav navbar\">\r\n\t\t\t\t\t\t<div class=\"navbar-menu\">\r\n\t\t\t\t\t\t\t<ul id=\"menu-services-menu\" class=\"menu\"><li id=\"menu-item-3489\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3489\"><a href=\"https:\/\/homeadaptfrance.com\/index.php\/air-conditioning\/\">Ventilation<\/a><\/li>\n<li id=\"menu-item-6659\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6659\"><a href=\"https:\/\/homeadaptfrance.com\/index.php\/empowering-sustainability\/\">Pompe \u00e0 chaleur<\/a><\/li>\n<li id=\"menu-item-6660\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6660\"><a href=\"https:\/\/homeadaptfrance.com\/index.php\/renewable-revolution\/\">Chaudi\u00e8re \u00e0 granules<\/a><\/li>\n<li id=\"menu-item-6661\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6661\"><a href=\"https:\/\/homeadaptfrance.com\/index.php\/green-energy-solution\/\">Panneaux Photovoltaiques<\/a><\/li>\n<li id=\"menu-item-6662\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6662\"><a href=\"https:\/\/homeadaptfrance.com\/index.php\/hydropower-solutions\/\">Chauffe eau solaire<\/a><\/li>\n<li id=\"menu-item-6663\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6663\"><a href=\"https:\/\/homeadaptfrance.com\/index.php\/integrated-water-energy\/\">Poele \u00e0 granul\u00e9s<\/a><\/li>\n<\/ul>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/nav>\r\n\t\t\t\t\t\t\t\t<\/div>\t\t\t\r\n\t\t\t\r\n\t\t<div class=\"sidebarmenu-area text-right mobilehum \">                                    \r\n\t\t\t<ul class=\"offcanvas-icon layout-1\">\r\n\t\t\t\t\t<li class=\"nav-link-container center\"> \r\n\t\t\t\t\t\t<a href=\"#\" class=\"nav-menu-link menu-button\">\r\n\t\t\t\t\t\t\t<svg width=\"20\" height=\"16\" viewBox=\"0 0 20 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\r\n\t\t\t\t\t\t\t\t<rect y=\"14\" width=\"18\" height=\"2\" fill=\"#ffffff\"><\/rect>\r\n\t\t\t\t\t\t\t\t<rect y=\"7\" width=\"18\" height=\"2\" fill=\"#ffffff\"><\/rect>\r\n\t\t\t\t\t\t\t\t<rect width=\"18\" height=\"2\" fill=\"#ffffff\"><\/rect>\r\n\t\t\t\t\t\t\t<\/svg>\r\n\t\t\t\t\t\t<\/a> \r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t<\/ul>                                      \r\n\t\t<\/div>      \r\n\t\t<\/div>\r\n\t<\/div>\t\t \r\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ed944eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ed944eb\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-68082f4\" data-id=\"68082f4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c430070 elementor-widget elementor-widget-image\" data-id=\"c430070\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"296\" height=\"220\" src=\"https:\/\/homeadaptfrance.com\/wp-content\/uploads\/2023\/08\/03-2.jpg\" class=\"attachment-large size-large wp-image-6610\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3032859 elementor-widget elementor-widget-topbar-icon-list\" data-id=\"3032859\" data-element_type=\"widget\" data-widget_type=\"topbar-icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t \n\n        <div class=\"rt-features-list-content\">                \n            <ul class=\"rt-features-list separator_no border_no rotate_no\">\n                    <li>\n                                                    <div class=\"icon\"><\/div>                            \n                                                                        <div class=\"query-list\">\n                            <span class=\"sub-text\"><\/span>\n                                                            <a href=\"tel:0186962912\"><span class=\"text-heading\">01 86 96 29 12 <\/span><\/a>\n                                                                                    <\/div>                        \n                    <\/li>\n                \n            <\/ul>                          \n        <\/div>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b22e942 elementor-widget elementor-widget-text-editor\" data-id=\"b22e942\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Lundi- Vendredi: 8:00-18:00<br \/><br \/><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05afa0c elementor-widget elementor-widget-react-button\" data-id=\"05afa0c\" data-element_type=\"widget\" data-widget_type=\"react-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\r\n\t\t\r\n\t\t<div class=\"react-button primary_btn\">\r\n\t\t\t\t\t\t<a class=\"react_button  center\" href=\"https:\/\/solari.themewant.com\/contact\/\" >\t\t\t\t\r\n\t\t\t\r\n\t\t\t\t\r\n\t\t\t<span class=\"btn_text\">Contactez-nous <\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t<\/div>    \r\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a1e1fae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a1e1fae\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3b940b3\" data-id=\"3b940b3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3c6de1 elementor-widget elementor-widget-topbar-icon-list\" data-id=\"f3c6de1\" data-element_type=\"widget\" data-widget_type=\"topbar-icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t \n\n        <div class=\"rt-features-list-content\">                \n            <ul class=\"rt-features-list separator_no border_no rotate_no\">\n                    <li>\n                                                    <div class=\"icon\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-envelope-open\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M494.586 164.516c-4.697-3.883-111.723-89.95-135.251-108.657C337.231 38.191 299.437 0 256 0c-43.205 0-80.636 37.717-103.335 55.859-24.463 19.45-131.07 105.195-135.15 108.549A48.004 48.004 0 0 0 0 201.485V464c0 26.51 21.49 48 48 48h416c26.51 0 48-21.49 48-48V201.509a48 48 0 0 0-17.414-36.993zM464 458a6 6 0 0 1-6 6H54a6 6 0 0 1-6-6V204.347c0-1.813.816-3.526 2.226-4.665 15.87-12.814 108.793-87.554 132.364-106.293C200.755 78.88 232.398 48 256 48c23.693 0 55.857 31.369 73.41 45.389 23.573 18.741 116.503 93.493 132.366 106.316a5.99 5.99 0 0 1 2.224 4.663V458zm-31.991-187.704c4.249 5.159 3.465 12.795-1.745 16.981-28.975 23.283-59.274 47.597-70.929 56.863C336.636 362.283 299.205 400 256 400c-43.452 0-81.287-38.237-103.335-55.86-11.279-8.967-41.744-33.413-70.927-56.865-5.21-4.187-5.993-11.822-1.745-16.981l15.258-18.528c4.178-5.073 11.657-5.843 16.779-1.726 28.618 23.001 58.566 47.035 70.56 56.571C200.143 320.631 232.307 352 256 352c23.602 0 55.246-30.88 73.41-45.389 11.994-9.535 41.944-33.57 70.563-56.568 5.122-4.116 12.601-3.346 16.778 1.727l15.258 18.526z\"><\/path><\/svg><\/div>                            \n                                                                        <div class=\"query-list\">\n                            <span class=\"sub-text\"><\/span>\n                                                            <a href=\"mailto:contact@homeadaptfrance.com\"><span class=\"text-heading\">contact@homeadaptfrance.com<\/span><\/a>                            \n                                                                                <\/div>                        \n                    <\/li>\n                \n            <\/ul>                          \n        <\/div>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6da605a elementor-widget elementor-widget-topbar-icon-list\" data-id=\"6da605a\" data-element_type=\"widget\" data-widget_type=\"topbar-icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t \n\n        <div class=\"rt-features-list-content\">                \n            <ul class=\"rt-features-list separator_no border_no rotate_no\">\n                    <li>\n                                                    <div class=\"icon\"><i aria-hidden=\"true\" class=\"rt rt-phone-flip\"><\/i><\/div>                            \n                                                                        <div class=\"query-list\">\n                            <span class=\"sub-text\"><\/span>\n                                                            <a href=\"tel:0186962912\"><span class=\"text-heading\">01 86 96 29 12<\/span><\/a>\n                                                                                    <\/div>                        \n                    <\/li>\n                \n            <\/ul>                          \n        <\/div>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fd04e3 elementor-widget elementor-widget-topbar-icon-list\" data-id=\"8fd04e3\" data-element_type=\"widget\" data-widget_type=\"topbar-icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t \n\n        <div class=\"rt-features-list-content\">                \n            <ul class=\"rt-features-list separator_no border_no rotate_no\">\n                    <li>\n                                                    <div class=\"icon\"><i aria-hidden=\"true\" class=\"rt rt-location-dot\"><\/i><\/div>                            \n                                                                        <div class=\"query-list\">\n                            <span class=\"sub-text\"><\/span>\n                                                            <span class=\"text-heading\">19 rue du Mus\u00e9e<\/span>\n                                                                                <\/div>                        \n                    <\/li>\n                \n            <\/ul>                          \n        <\/div>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2c3533 elementor-widget elementor-widget-topbar-icon-list\" data-id=\"d2c3533\" data-element_type=\"widget\" data-widget_type=\"topbar-icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t \n\n        <div class=\"rt-features-list-content\">                \n            <ul class=\"rt-features-list separator_no border_no rotate_no\">\n                    <li>\n                                                    <div class=\"icon\"><i aria-hidden=\"true\" class=\"rt rt-location-dot\"><\/i><\/div>                            \n                                                                        <div class=\"query-list\">\n                            <span class=\"sub-text\"><\/span>\n                                                            <span class=\"text-heading\">Marseille<\/span>\n                                                                                <\/div>                        \n                    <\/li>\n                \n            <\/ul>                          \n        <\/div>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La pompe \u00e0 chaleur une \u00e9cologie et efficacit\u00e9 pour un confort durable La pompe \u00e0 chaleur repr\u00e9sente une solution innovante et \u00e9cologique dans le domaine du chauffage. Fonctionnant de mani\u00e8re ing\u00e9nieuse, elle extrait la chaleur de l&#8217;air, de l&#8217;eau ou du sol pour la redistribuer \u00e0 l&#8217;int\u00e9rieur d&#8217;un espace, que ce soit pour le chauffage&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/homeadaptfrance.com\/index.php\/wp-json\/wp\/v2\/pages\/6654"}],"collection":[{"href":"https:\/\/homeadaptfrance.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/homeadaptfrance.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/homeadaptfrance.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/homeadaptfrance.com\/index.php\/wp-json\/wp\/v2\/comments?post=6654"}],"version-history":[{"count":14,"href":"https:\/\/homeadaptfrance.com\/index.php\/wp-json\/wp\/v2\/pages\/6654\/revisions"}],"predecessor-version":[{"id":8887,"href":"https:\/\/homeadaptfrance.com\/index.php\/wp-json\/wp\/v2\/pages\/6654\/revisions\/8887"}],"wp:attachment":[{"href":"https:\/\/homeadaptfrance.com\/index.php\/wp-json\/wp\/v2\/media?parent=6654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}